{"id":32047,"date":"2026-02-17T14:59:26","date_gmt":"2026-02-17T14:59:26","guid":{"rendered":"https:\/\/diarioahora.com.ar\/?p=32047"},"modified":"2026-02-17T14:59:26","modified_gmt":"2026-02-17T14:59:26","slug":"el-senador-francisco-paoltroni-senalo-que-los-privilegiados-del-modelo-formosenos-son-los-funcionarios-gildistas-y-los-empresarios-proveedores-del-estado-el-resto-de-los-formosenos-vive-en-la-p","status":"publish","type":"post","link":"https:\/\/diarioahora.com.ar\/index.php\/2026\/02\/17\/el-senador-francisco-paoltroni-senalo-que-los-privilegiados-del-modelo-formosenos-son-los-funcionarios-gildistas-y-los-empresarios-proveedores-del-estado-el-resto-de-los-formosenos-vive-en-la-p\/","title":{"rendered":"El senador Francisco Paoltroni se\u00f1al\u00f3 que los privilegiados del &#8220;Modelo Formose\u00f1os&#8221; son los funcionarios gildistas y los empresarios proveedores del estado, &#8220;el resto de los formose\u00f1os vive en la pobreza&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El senador por Formosa, y del bloque de la Libertad Avanza, brind\u00f3 una entrevista por Radio Parque y apunt\u00f3 al gobierno de Gildo Insfr\u00e1n y se\u00f1al\u00f3 que los \u00fanicos privilegiados del Modelo Formose\u00f1os son los funcionarios y los empresarios proveedores del estado.  <\/p>\n\n\n\n<iframe src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&#038;href=https%3A%2F%2Fwww.facebook.com%2FRadioParqueFM89.3%2Fvideos%2F25959254960353815%2F&#038;show_text=false&#038;width=560&#038;t=0\" width=\"560\" height=\"314\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" allowFullScreen=\"true\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>El senador por Formosa, y del bloque de la Libertad Avanza, brind\u00f3 una entrevista por Radio Parque y apunt\u00f3 al gobierno de Gildo Insfr\u00e1n y&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-32047","post","type-post","status-publish","format-standard","hentry","category-formosa","entry","double"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=32047"}],"version-history":[{"count":1,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32047\/revisions"}],"predecessor-version":[{"id":32049,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/32047\/revisions\/32049"}],"wp:attachment":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=32047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=32047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=32047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}