{"id":31838,"date":"2026-02-10T13:18:48","date_gmt":"2026-02-10T13:18:48","guid":{"rendered":"https:\/\/diarioahora.com.ar\/?p=31838"},"modified":"2026-02-10T13:31:29","modified_gmt":"2026-02-10T13:31:29","slug":"la-secretaria-de-accion-social-del-municipio-de-formosa-confirmo-que-en-marzo-se-inaugurara-la-primer-guarderia-infantil-municipal","status":"publish","type":"post","link":"https:\/\/diarioahora.com.ar\/index.php\/2026\/02\/10\/la-secretaria-de-accion-social-del-municipio-de-formosa-confirmo-que-en-marzo-se-inaugurara-la-primer-guarderia-infantil-municipal\/","title":{"rendered":"La secretaria de Acci\u00f3n Social del Municipio de Formosa confirm\u00f3 que en marzo se inaugurar\u00e1 la primer guarder\u00eda infantil municipal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Municipalidad de Formosa anunci\u00f3 la inauguraci\u00f3n de una guarder\u00eda destinada exclusivamente a los hijos del personal municipal. El nuevo espacio funcionar\u00e1 dentro de la renovada <em>Casa del Trabajador Municipal<\/em>, ubicada sobre la calle Rivadavia, entre Ayacucho y Salta, y comenzar\u00e1 a operar en el mes de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa responde a una demanda hist\u00f3rica de las familias municipales, que hasta ahora no contaban con un lugar seguro donde dejar a sus hijos durante la jornada laboral o de estudios. Se trata de la primera vez en la historia institucional de la ciudad que se habilita un servicio de estas caracter\u00edsticas, marcando un hito en materia de bienestar y derechos para los trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La responsable de la Secretar\u00eda de Acci\u00f3n Social del municipio capitalino, Lic. Paula Catt\u00e1neo, confirm\u00f3 la noticia en una entrevista con el periodista Tyntu Ru\u00edz durante el fin de semana. Seg\u00fan explic\u00f3, se est\u00e1n ultimando los detalles para la habilitaci\u00f3n formal y el objetivo es facilitar la conciliaci\u00f3n entre la vida laboral y familiar de los empleados municipales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proyecto se enmarca en la pol\u00edtica de mejora de servicios impulsada por la actual gesti\u00f3n del intendente Jorge Jofr\u00e9, que busca fortalecer el acompa\u00f1amiento a los trabajadores y garantizar un entorno seguro para la infancia. Con la apertura de la guarder\u00eda, la Municipalidad de Formosa pone en valor la importancia de brindar soluciones concretas a las necesidades cotidianas de su personal, consolidando un paso significativo hacia una ciudad m\u00e1s inclusiva y comprometida con el bienestar de su comunidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Formosa anunci\u00f3 la inauguraci\u00f3n de una guarder\u00eda destinada exclusivamente a los hijos del personal municipal. El nuevo espacio funcionar\u00e1 dentro de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-31838","post","type-post","status-publish","format-standard","hentry","category-formosa","entry","double"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31838"}],"version-history":[{"count":3,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31838\/revisions"}],"predecessor-version":[{"id":31843,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31838\/revisions\/31843"}],"wp:attachment":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}