{"id":31803,"date":"2026-02-09T18:37:01","date_gmt":"2026-02-09T18:37:01","guid":{"rendered":"https:\/\/diarioahora.com.ar\/?p=31803"},"modified":"2026-02-09T18:38:18","modified_gmt":"2026-02-09T18:38:18","slug":"conflictos-de-viviendas-del-ipv-el-ex-diputado-provincial-lopez-guaymas-habria-accedido-a-tres-viviendas-en-el-barrio-ibira-pyta","status":"publish","type":"post","link":"https:\/\/diarioahora.com.ar\/index.php\/2026\/02\/09\/conflictos-de-viviendas-del-ipv-el-ex-diputado-provincial-lopez-guaymas-habria-accedido-a-tres-viviendas-en-el-barrio-ibira-pyta\/","title":{"rendered":"Conflictos de viviendas del IPV: El ex diputado provincial por el gildismo, L\u00f3pez Guaymas habr\u00eda accedido a tres viviendas en el barrio Ibir\u00e1 Pyt\u00e1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En medio de los reclamos de mujeres que exigen soluciones habitacionales al Instituto Provincial de la Vivienda (IPV), sali\u00f3 a la luz un caso que reaviva el debate sobre el acceso desigual a estas casas. Vecinos del barrio Ibir\u00e1 Pyt\u00e1, en la ciudad capital, confirmaron que el exdiputado gildista L\u00f3pez Guaymas habr\u00eda sido adjudicatario con tres viviendas del IPV, algo expresamente prohibido por la normativa vigente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de las unidades ubicadas en la manzana 245, casas n\u00fameros 5 y 6 frente a la calle principal y una tercera, la n\u00famero 13, que funcionar\u00eda como el patio trasero del domicilio del exfuncionario. Seg\u00fan el reglamento para acceder a viviendas del FO.NA.VI., ning\u00fan beneficiario puede ser adjudicado con m\u00e1s de un inmueble, lo que convierte este caso en un ejemplo de irregularidad. Tras el fallecimiento de L\u00f3pez Guaymas, las viviendas habr\u00edan quedado en manos de sus hijos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El episodio expone una problem\u00e1tica recurrente: mientras ciudadanos comunes enfrentan largas listas de espera y requisitos estrictos para acceder a una vivienda, algunos funcionarios del gobierno provincial parecen contar con facilidades excepcionales. La situaci\u00f3n genera indignaci\u00f3n y abre un debate m\u00e1s amplio sobre la transparencia en la adjudicaci\u00f3n de viviendas sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de los reclamos de mujeres que exigen soluciones habitacionales al Instituto Provincial de la Vivienda (IPV), sali\u00f3 a la luz un caso que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-31803","post","type-post","status-publish","format-standard","hentry","category-formosa","entry","double"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31803"}],"version-history":[{"count":2,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31803\/revisions"}],"predecessor-version":[{"id":31806,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31803\/revisions\/31806"}],"wp:attachment":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}