{"id":31415,"date":"2026-01-29T01:46:33","date_gmt":"2026-01-29T01:46:33","guid":{"rendered":"https:\/\/diarioahora.com.ar\/?p=31415"},"modified":"2026-01-29T01:46:33","modified_gmt":"2026-01-29T01:46:33","slug":"el-municipio-de-formosa-informo-que-este-jueves-el-castramovil-brindara-servicio-de-atencion-veterinaria-en-el-bo-ex-villa-lote-110","status":"publish","type":"post","link":"https:\/\/diarioahora.com.ar\/index.php\/2026\/01\/29\/el-municipio-de-formosa-informo-que-este-jueves-el-castramovil-brindara-servicio-de-atencion-veterinaria-en-el-bo-ex-villa-lote-110\/","title":{"rendered":"El municipio de Formosa inform\u00f3 que este jueves el castram\u00f3vil brindar\u00e1 servicio de atenci\u00f3n veterinaria en el B\u00ba ex villa Lote 110"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde la Direcci\u00f3n de Zoonosis dependiente de la Secretar\u00eda de Acci\u00f3n Social de la Municipalidad se inform\u00f3 que este jueves 29, el Castram\u00f3vil Municipal regresar\u00e1 al barrio 28 de junio (ex Lote 110) para desarrollar un nuevo operativo sanitario gratuito destinado a perros y gatos. La actividad se llevar\u00e1 a cabo en la canchita \u201cPeque\u00f1os Valores\u201d, en el horario de 8 a 12 horas, donde se brindar\u00e1n servicios de castraci\u00f3n, vacunaci\u00f3n antirr\u00e1bica y desparasitaci\u00f3n, sin ning\u00fan tipo de costo para los vecinos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el \u00e1rea explicaron que el operativo dar\u00e1 continuidad a la jornada realizada la semana pasada en el mismo sector, en la que los vecinos se fueron anotando y se conform\u00f3 una lista de turnos. En ese sentido, la atenci\u00f3n de este jueves estar\u00e1 orientada principalmente a cumplir con los turnos ya otorgados. No obstante, se inform\u00f3 que podr\u00edan habilitarse algunos cupos disponibles, en caso de que alguna de las personas inscriptas previamente no pueda asistir. Para acceder a los turnos de castraci\u00f3n, los interesados deben comunicarse al 3704605703, enviando un mensaje de WhatsApp con la palabra \u201cCastram\u00f3vil\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas acciones, el Municipio contin\u00faa fortaleciendo las pol\u00edticas de salud p\u00fablica y protecci\u00f3n animal, acercando servicios esenciales a los distintos barrios de la ciudad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Direcci\u00f3n de Zoonosis dependiente de la Secretar\u00eda de Acci\u00f3n Social de la Municipalidad se inform\u00f3 que este jueves 29, el Castram\u00f3vil Municipal regresar\u00e1&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-31415","post","type-post","status-publish","format-standard","hentry","category-formosa","entry","double"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31415"}],"version-history":[{"count":1,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31415\/revisions"}],"predecessor-version":[{"id":31417,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31415\/revisions\/31417"}],"wp:attachment":[{"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioahora.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}